{"id":10700,"date":"2025-01-19T17:35:51","date_gmt":"2025-01-19T20:35:51","guid":{"rendered":"https:\/\/floripaquilt.com.br\/2025\/?post_type=product&#038;p=10700"},"modified":"2025-03-21T17:00:33","modified_gmt":"2025-03-21T20:00:33","slug":"03-05-boneca-valentina-lilian-rossato","status":"publish","type":"product","link":"https:\/\/floripaquilt.com.br\/2025\/produto\/03-05-boneca-valentina-lilian-rossato\/","title":{"rendered":"03\/05 \u2013 Boneca Valentina (Lilian Rossato)"},"content":{"rendered":"<p><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">[gtraduzir]<\/span><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">R$ 250,00<\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/strong><\/p>\n<p><strong>Por:<\/strong> <strong>Lilian Rossato, SP\/Brasil.<\/strong><\/p>\n<p><strong>Data:\u202f<\/strong>3 de maio \u2013 s\u00e1bado<\/p>\n<p><strong>Carga hor\u00e1ria<\/strong>: 8h \u00e0s 12h \u2013 4h\/a<\/p>\n<p><strong>Descritivo:<\/strong> Boneca artesanal medindo 45 cm, confeccionada em tecido tricoline, com um kit completo inclu\u00eddo. O kit ser\u00e1 entregue costurado e parcialmente preenchido, pronto para voc\u00ea finalizar com nosso passo a passo. Juntas, vamos aprender: Costura do corpo e das roupas da boneca, t\u00e9cnicas de pintura para as asas e o rostinho, como envelhecer a casinha e tingir os tecidos para um efeito vintage, dicas para a escolha e aplica\u00e7\u00e3o do cabelo e por fim o segredo para deixar o pesco\u00e7o da boneca firme e bem estruturado. Transforme seu kit em uma pe\u00e7a \u00fanica e encantadora, com acabamentos personalizados e toques especiais.<\/p>\n<p><strong>Pr\u00e9-requisitos<\/strong>: Gostar do fazer \u00e0 m\u00e3o.<\/p>\n<p><strong>Material necess\u00e1rio: <\/strong>Agulha para costura \u00e0 m\u00e3o, linha branca ou bege e tesoura..<\/p>\n<p><strong>Observa\u00e7\u00f5es:\u00a0<\/strong><\/p>\n<p>O\u00a0material solicitado \u00e9 imprescind\u00edvel para participa\u00e7\u00e3o no curso\/oficina.<\/p>\n<p>Atente-se para n\u00e3o comprar cursos\/oficinas no mesmo dia e hor\u00e1rio.<\/p>\n<p>Ap\u00f3s o pagamento, a sua matr\u00edcula \u00e9 automaticamente confirmada no curso\/oficina escolhido, portanto\u00a0<strong>n\u00e3o h\u00e1 possibilidade de reembolso dos valores.<\/strong><\/p>\n<p>Em caso de desist\u00eancia, sua inscri\u00e7\u00e3o poder\u00e1 ser transferida para outra pessoa por indica\u00e7\u00e3o enviando os dados da compra e da pessoa que vir\u00e1 no seu lugar para o email: <a href=\"mailto:fqcursos@gmail.com\">fqcursos@gmail.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">[gtraduzir]<\/span><\/span><\/span><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">R$ 250,00<\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/strong><\/p>\n<p><strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Por:<\/span><\/span><\/span><\/span><\/strong> <strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Lilian Rossato, SP\/Brasil.<\/span><\/span><\/span><\/span><\/strong><\/p>\n<p><strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Data:\u202f<\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">3 de maio \u2013 s\u00e1bado<\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/p>\n<p><strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Carga hor\u00e1ria<\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">: 8h \u00e0s 12h \u2013 4h\/a<\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/p>\n<p><strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Descritivo:<\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"> Boneca artesanal medindo 45 cm, confeccionada em tecido tricoline, com um kit completo inclu\u00eddo. O kit ser\u00e1 entregue costurado e parcialmente preenchido, pronto para voc\u00ea finalizar com nosso passo a passo. Juntas, vamos aprender: Costura do corpo e das roupas da boneca, t\u00e9cnicas de pintura para as asas e o rostinho, como envelhecer a casinha e tingir os tecidos para um efeito vintage, dicas para a escolha e aplica\u00e7\u00e3o do cabelo e por fim o segredo para deixar o pesco\u00e7o da boneca firme e bem estruturado. Transforme seu kit em uma pe\u00e7a \u00fanica e encantadora, com acabamentos personalizados e toques especiais.<\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/p>\n<p><strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Pr\u00e9-requisitos<\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">: Gostar do fazer \u00e0 m\u00e3o.<\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/p>\n<p><strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Material necess\u00e1rio: <\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Agulha para costura \u00e0 m\u00e3o, linha branca ou bege e tesoura..<\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/p>\n<p><strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Observa\u00e7\u00f5es:\u00a0<\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/strong><\/p>\n<p><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">O\u00a0material solicitado \u00e9 imprescind\u00edvel para participa\u00e7\u00e3o no curso\/oficina.<\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/p>\n<p><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Atente-se para n\u00e3o comprar cursos\/oficinas no mesmo dia e hor\u00e1rio.<\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/p>\n<p><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Ap\u00f3s o pagamento, a sua matr\u00edcula \u00e9 automaticamente confirmada no curso\/oficina escolhido, portanto\u00a0<\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">n\u00e3o h\u00e1 possibilidade de reembolso dos valores.<\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/strong><\/p>\n<p><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Em caso de desist\u00eancia, sua inscri\u00e7\u00e3o poder\u00e1 ser transferida para outra pessoa por indica\u00e7\u00e3o enviando os dados da compra e da pessoa que vir\u00e1 no seu lugar para o email: <\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><a href=\"mailto:fqcursos@gmail.com\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">fqcursos@gmail.com<\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/a><\/p>\n","protected":false},"featured_media":10738,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false},"product_brand":[],"product_cat":[155],"product_tag":[],"class_list":["post-10700","product","type-product","status-publish","has-post-thumbnail","product_cat-oficinas","first","instock","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>03\/05 \u2013 Boneca Valentina (Lilian Rossato) - Floripa Quilt<\/title>\n<meta name=\"description\" content=\"R$ 250,00 Por: Lilian Rossato, SP\/Brasil. Data:\u202f3 de maio \u2013 s\u00e1bado Carga hor\u00e1ria: 8h \u00e0s 12h \u2013 4h\/a Descritivo: Boneca artesanal medindo 45 cm, confeccionada em tecido tricoline, com um kit completo inclu\u00eddo. O kit ser\u00e1 entregue costurado e parcialmente preenchido, pronto para voc\u00ea finalizar com nosso passo a passo. Juntas, vamos aprender: Costura do corpo e das roupas da boneca, t\u00e9cnicas de pintura para as asas e o rostinho, como envelhecer a casinha e tingir os tecidos para um efeito vintage, dicas para a escolha e aplica\u00e7\u00e3o do cabelo e por fim o segredo para deixar o pesco\u00e7o da boneca firme e bem estruturado. Transforme seu kit em uma pe\u00e7a \u00fanica e encantadora, com acabamentos personalizados e toques especiais.Pr\u00e9-requisitos: Gostar do fazer \u00e0 m\u00e3o.Material necess\u00e1rio: Agulha para costura \u00e0 m\u00e3o, linha branca ou bege e tesoura..Observa\u00e7\u00f5es: O material solicitado \u00e9 imprescind\u00edvel para participa\u00e7\u00e3o no curso\/oficina.Atente-se para n\u00e3o comprar cursos\/oficinas no mesmo dia e hor\u00e1rio.Ap\u00f3s o pagamento, a sua matr\u00edcula \u00e9 automaticamente confirmada no curso\/oficina escolhido, portanto n\u00e3o h\u00e1 possibilidade de reembolso dos valores.Em caso de desist\u00eancia, sua inscri\u00e7\u00e3o poder\u00e1 ser transferida para outra pessoa por indica\u00e7\u00e3o enviando os dados da compra e da pessoa que vir\u00e1 no seu lugar para o email: fqcursos@gmail.com\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/floripaquilt.com.br\/2025\/produto\/03-05-boneca-valentina-lilian-rossato\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"03\/05 \u2013 Boneca Valentina (Lilian Rossato) - Floripa Quilt\" \/>\n<meta property=\"og:description\" content=\"R$ 250,00 Por: Lilian Rossato, SP\/Brasil. Data:\u202f3 de maio \u2013 s\u00e1bado Carga hor\u00e1ria: 8h \u00e0s 12h \u2013 4h\/a Descritivo: Boneca artesanal medindo 45 cm, confeccionada em tecido tricoline, com um kit completo inclu\u00eddo. O kit ser\u00e1 entregue costurado e parcialmente preenchido, pronto para voc\u00ea finalizar com nosso passo a passo. Juntas, vamos aprender: Costura do corpo e das roupas da boneca, t\u00e9cnicas de pintura para as asas e o rostinho, como envelhecer a casinha e tingir os tecidos para um efeito vintage, dicas para a escolha e aplica\u00e7\u00e3o do cabelo e por fim o segredo para deixar o pesco\u00e7o da boneca firme e bem estruturado. Transforme seu kit em uma pe\u00e7a \u00fanica e encantadora, com acabamentos personalizados e toques especiais.Pr\u00e9-requisitos: Gostar do fazer \u00e0 m\u00e3o.Material necess\u00e1rio: Agulha para costura \u00e0 m\u00e3o, linha branca ou bege e tesoura..Observa\u00e7\u00f5es: O material solicitado \u00e9 imprescind\u00edvel para participa\u00e7\u00e3o no curso\/oficina.Atente-se para n\u00e3o comprar cursos\/oficinas no mesmo dia e hor\u00e1rio.Ap\u00f3s o pagamento, a sua matr\u00edcula \u00e9 automaticamente confirmada no curso\/oficina escolhido, portanto n\u00e3o h\u00e1 possibilidade de reembolso dos valores.Em caso de desist\u00eancia, sua inscri\u00e7\u00e3o poder\u00e1 ser transferida para outra pessoa por indica\u00e7\u00e3o enviando os dados da compra e da pessoa que vir\u00e1 no seu lugar para o email: fqcursos@gmail.com\" \/>\n<meta property=\"og:url\" content=\"https:\/\/floripaquilt.com.br\/2025\/produto\/03-05-boneca-valentina-lilian-rossato\/\" \/>\n<meta property=\"og:site_name\" content=\"Floripa Quilt\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-21T20:00:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/floripaquilt.com.br\/2025\/wp-content\/uploads\/2025\/01\/WhatsApp-Image-2025-01-20-at-09.01.13.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1512\" \/>\n\t<meta property=\"og:image:height\" content=\"1512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/floripaquilt.com.br\\\/2025\\\/produto\\\/03-05-boneca-valentina-lilian-rossato\\\/\",\"url\":\"https:\\\/\\\/floripaquilt.com.br\\\/2025\\\/produto\\\/03-05-boneca-valentina-lilian-rossato\\\/\",\"name\":\"03\\\/05 \u2013 Boneca Valentina (Lilian Rossato) - Floripa Quilt\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/floripaquilt.com.br\\\/2025\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/floripaquilt.com.br\\\/2025\\\/produto\\\/03-05-boneca-valentina-lilian-rossato\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/floripaquilt.com.br\\\/2025\\\/produto\\\/03-05-boneca-valentina-lilian-rossato\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/floripaquilt.com.br\\\/2025\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/WhatsApp-Image-2025-01-20-at-09.01.13.jpeg\",\"datePublished\":\"2025-01-19T20:35:51+00:00\",\"dateModified\":\"2025-03-21T20:00:33+00:00\",\"description\":\"R$ 250,00 Por: Lilian Rossato, SP\\\/Brasil. Data:\u202f3 de maio \u2013 s\u00e1bado Carga hor\u00e1ria: 8h \u00e0s 12h \u2013 4h\\\/a Descritivo: Boneca artesanal medindo 45 cm, confeccionada em tecido tricoline, com um kit completo inclu\u00eddo. O kit ser\u00e1 entregue costurado e parcialmente preenchido, pronto para voc\u00ea finalizar com nosso passo a passo. Juntas, vamos aprender: Costura do corpo e das roupas da boneca, t\u00e9cnicas de pintura para as asas e o rostinho, como envelhecer a casinha e tingir os tecidos para um efeito vintage, dicas para a escolha e aplica\u00e7\u00e3o do cabelo e por fim o segredo para deixar o pesco\u00e7o da boneca firme e bem estruturado. Transforme seu kit em uma pe\u00e7a \u00fanica e encantadora, com acabamentos personalizados e toques especiais.Pr\u00e9-requisitos: Gostar do fazer \u00e0 m\u00e3o.Material necess\u00e1rio: Agulha para costura \u00e0 m\u00e3o, linha branca ou bege e tesoura..Observa\u00e7\u00f5es: O material solicitado \u00e9 imprescind\u00edvel para participa\u00e7\u00e3o no curso\\\/oficina.Atente-se para n\u00e3o comprar cursos\\\/oficinas no mesmo dia e hor\u00e1rio.Ap\u00f3s o pagamento, a sua matr\u00edcula \u00e9 automaticamente confirmada no curso\\\/oficina escolhido, portanto n\u00e3o h\u00e1 possibilidade de reembolso dos valores.Em caso de desist\u00eancia, sua inscri\u00e7\u00e3o poder\u00e1 ser transferida para outra pessoa por indica\u00e7\u00e3o enviando os dados da compra e da pessoa que vir\u00e1 no seu lugar para o email: fqcursos@gmail.com\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/floripaquilt.com.br\\\/2025\\\/produto\\\/03-05-boneca-valentina-lilian-rossato\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/floripaquilt.com.br\\\/2025\\\/produto\\\/03-05-boneca-valentina-lilian-rossato\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/floripaquilt.com.br\\\/2025\\\/produto\\\/03-05-boneca-valentina-lilian-rossato\\\/#primaryimage\",\"url\":\"https:\\\/\\\/floripaquilt.com.br\\\/2025\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/WhatsApp-Image-2025-01-20-at-09.01.13.jpeg\",\"contentUrl\":\"https:\\\/\\\/floripaquilt.com.br\\\/2025\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/WhatsApp-Image-2025-01-20-at-09.01.13.jpeg\",\"width\":1512,\"height\":1512},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/floripaquilt.com.br\\\/2025\\\/produto\\\/03-05-boneca-valentina-lilian-rossato\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/floripaquilt.com.br\\\/2025\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"03\\\/05 \u2013 Boneca Valentina (Lilian Rossato)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/floripaquilt.com.br\\\/2025\\\/#website\",\"url\":\"https:\\\/\\\/floripaquilt.com.br\\\/2025\\\/\",\"name\":\"Floripa Quilt\",\"description\":\"Floripa Quilt 2025 - 12\u00ba Festival de Patchwork - Arte T\u00eaxtil\",\"publisher\":{\"@id\":\"https:\\\/\\\/floripaquilt.com.br\\\/2025\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/floripaquilt.com.br\\\/2025\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/floripaquilt.com.br\\\/2025\\\/#organization\",\"name\":\"Floripa Quilt\",\"url\":\"https:\\\/\\\/floripaquilt.com.br\\\/2025\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/floripaquilt.com.br\\\/2025\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/floripaquilt.com.br\\\/2025\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/cropped-Sem-titulo-15.png\",\"contentUrl\":\"https:\\\/\\\/floripaquilt.com.br\\\/2025\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/cropped-Sem-titulo-15.png\",\"width\":3938,\"height\":669,\"caption\":\"Floripa Quilt\"},\"image\":{\"@id\":\"https:\\\/\\\/floripaquilt.com.br\\\/2025\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"03\/05 \u2013 Boneca Valentina (Lilian Rossato) - Floripa Quilt","description":"R$ 250,00 Por: Lilian Rossato, SP\/Brasil. Data:\u202f3 de maio \u2013 s\u00e1bado Carga hor\u00e1ria: 8h \u00e0s 12h \u2013 4h\/a Descritivo: Boneca artesanal medindo 45 cm, confeccionada em tecido tricoline, com um kit completo inclu\u00eddo. O kit ser\u00e1 entregue costurado e parcialmente preenchido, pronto para voc\u00ea finalizar com nosso passo a passo. Juntas, vamos aprender: Costura do corpo e das roupas da boneca, t\u00e9cnicas de pintura para as asas e o rostinho, como envelhecer a casinha e tingir os tecidos para um efeito vintage, dicas para a escolha e aplica\u00e7\u00e3o do cabelo e por fim o segredo para deixar o pesco\u00e7o da boneca firme e bem estruturado. Transforme seu kit em uma pe\u00e7a \u00fanica e encantadora, com acabamentos personalizados e toques especiais.Pr\u00e9-requisitos: Gostar do fazer \u00e0 m\u00e3o.Material necess\u00e1rio: Agulha para costura \u00e0 m\u00e3o, linha branca ou bege e tesoura..Observa\u00e7\u00f5es: O material solicitado \u00e9 imprescind\u00edvel para participa\u00e7\u00e3o no curso\/oficina.Atente-se para n\u00e3o comprar cursos\/oficinas no mesmo dia e hor\u00e1rio.Ap\u00f3s o pagamento, a sua matr\u00edcula \u00e9 automaticamente confirmada no curso\/oficina escolhido, portanto n\u00e3o h\u00e1 possibilidade de reembolso dos valores.Em caso de desist\u00eancia, sua inscri\u00e7\u00e3o poder\u00e1 ser transferida para outra pessoa por indica\u00e7\u00e3o enviando os dados da compra e da pessoa que vir\u00e1 no seu lugar para o email: fqcursos@gmail.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/floripaquilt.com.br\/2025\/produto\/03-05-boneca-valentina-lilian-rossato\/","og_locale":"pt_BR","og_type":"article","og_title":"03\/05 \u2013 Boneca Valentina (Lilian Rossato) - Floripa Quilt","og_description":"R$ 250,00 Por: Lilian Rossato, SP\/Brasil. Data:\u202f3 de maio \u2013 s\u00e1bado Carga hor\u00e1ria: 8h \u00e0s 12h \u2013 4h\/a Descritivo: Boneca artesanal medindo 45 cm, confeccionada em tecido tricoline, com um kit completo inclu\u00eddo. O kit ser\u00e1 entregue costurado e parcialmente preenchido, pronto para voc\u00ea finalizar com nosso passo a passo. Juntas, vamos aprender: Costura do corpo e das roupas da boneca, t\u00e9cnicas de pintura para as asas e o rostinho, como envelhecer a casinha e tingir os tecidos para um efeito vintage, dicas para a escolha e aplica\u00e7\u00e3o do cabelo e por fim o segredo para deixar o pesco\u00e7o da boneca firme e bem estruturado. Transforme seu kit em uma pe\u00e7a \u00fanica e encantadora, com acabamentos personalizados e toques especiais.Pr\u00e9-requisitos: Gostar do fazer \u00e0 m\u00e3o.Material necess\u00e1rio: Agulha para costura \u00e0 m\u00e3o, linha branca ou bege e tesoura..Observa\u00e7\u00f5es: O material solicitado \u00e9 imprescind\u00edvel para participa\u00e7\u00e3o no curso\/oficina.Atente-se para n\u00e3o comprar cursos\/oficinas no mesmo dia e hor\u00e1rio.Ap\u00f3s o pagamento, a sua matr\u00edcula \u00e9 automaticamente confirmada no curso\/oficina escolhido, portanto n\u00e3o h\u00e1 possibilidade de reembolso dos valores.Em caso de desist\u00eancia, sua inscri\u00e7\u00e3o poder\u00e1 ser transferida para outra pessoa por indica\u00e7\u00e3o enviando os dados da compra e da pessoa que vir\u00e1 no seu lugar para o email: fqcursos@gmail.com","og_url":"https:\/\/floripaquilt.com.br\/2025\/produto\/03-05-boneca-valentina-lilian-rossato\/","og_site_name":"Floripa Quilt","article_modified_time":"2025-03-21T20:00:33+00:00","og_image":[{"width":1512,"height":1512,"url":"https:\/\/floripaquilt.com.br\/2025\/wp-content\/uploads\/2025\/01\/WhatsApp-Image-2025-01-20-at-09.01.13.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/floripaquilt.com.br\/2025\/produto\/03-05-boneca-valentina-lilian-rossato\/","url":"https:\/\/floripaquilt.com.br\/2025\/produto\/03-05-boneca-valentina-lilian-rossato\/","name":"03\/05 \u2013 Boneca Valentina (Lilian Rossato) - Floripa Quilt","isPartOf":{"@id":"https:\/\/floripaquilt.com.br\/2025\/#website"},"primaryImageOfPage":{"@id":"https:\/\/floripaquilt.com.br\/2025\/produto\/03-05-boneca-valentina-lilian-rossato\/#primaryimage"},"image":{"@id":"https:\/\/floripaquilt.com.br\/2025\/produto\/03-05-boneca-valentina-lilian-rossato\/#primaryimage"},"thumbnailUrl":"https:\/\/floripaquilt.com.br\/2025\/wp-content\/uploads\/2025\/01\/WhatsApp-Image-2025-01-20-at-09.01.13.jpeg","datePublished":"2025-01-19T20:35:51+00:00","dateModified":"2025-03-21T20:00:33+00:00","description":"R$ 250,00 Por: Lilian Rossato, SP\/Brasil. Data:\u202f3 de maio \u2013 s\u00e1bado Carga hor\u00e1ria: 8h \u00e0s 12h \u2013 4h\/a Descritivo: Boneca artesanal medindo 45 cm, confeccionada em tecido tricoline, com um kit completo inclu\u00eddo. O kit ser\u00e1 entregue costurado e parcialmente preenchido, pronto para voc\u00ea finalizar com nosso passo a passo. Juntas, vamos aprender: Costura do corpo e das roupas da boneca, t\u00e9cnicas de pintura para as asas e o rostinho, como envelhecer a casinha e tingir os tecidos para um efeito vintage, dicas para a escolha e aplica\u00e7\u00e3o do cabelo e por fim o segredo para deixar o pesco\u00e7o da boneca firme e bem estruturado. Transforme seu kit em uma pe\u00e7a \u00fanica e encantadora, com acabamentos personalizados e toques especiais.Pr\u00e9-requisitos: Gostar do fazer \u00e0 m\u00e3o.Material necess\u00e1rio: Agulha para costura \u00e0 m\u00e3o, linha branca ou bege e tesoura..Observa\u00e7\u00f5es: O material solicitado \u00e9 imprescind\u00edvel para participa\u00e7\u00e3o no curso\/oficina.Atente-se para n\u00e3o comprar cursos\/oficinas no mesmo dia e hor\u00e1rio.Ap\u00f3s o pagamento, a sua matr\u00edcula \u00e9 automaticamente confirmada no curso\/oficina escolhido, portanto n\u00e3o h\u00e1 possibilidade de reembolso dos valores.Em caso de desist\u00eancia, sua inscri\u00e7\u00e3o poder\u00e1 ser transferida para outra pessoa por indica\u00e7\u00e3o enviando os dados da compra e da pessoa que vir\u00e1 no seu lugar para o email: fqcursos@gmail.com","breadcrumb":{"@id":"https:\/\/floripaquilt.com.br\/2025\/produto\/03-05-boneca-valentina-lilian-rossato\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/floripaquilt.com.br\/2025\/produto\/03-05-boneca-valentina-lilian-rossato\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/floripaquilt.com.br\/2025\/produto\/03-05-boneca-valentina-lilian-rossato\/#primaryimage","url":"https:\/\/floripaquilt.com.br\/2025\/wp-content\/uploads\/2025\/01\/WhatsApp-Image-2025-01-20-at-09.01.13.jpeg","contentUrl":"https:\/\/floripaquilt.com.br\/2025\/wp-content\/uploads\/2025\/01\/WhatsApp-Image-2025-01-20-at-09.01.13.jpeg","width":1512,"height":1512},{"@type":"BreadcrumbList","@id":"https:\/\/floripaquilt.com.br\/2025\/produto\/03-05-boneca-valentina-lilian-rossato\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/floripaquilt.com.br\/2025\/"},{"@type":"ListItem","position":2,"name":"03\/05 \u2013 Boneca Valentina (Lilian Rossato)"}]},{"@type":"WebSite","@id":"https:\/\/floripaquilt.com.br\/2025\/#website","url":"https:\/\/floripaquilt.com.br\/2025\/","name":"Floripa Quilt","description":"Floripa Quilt 2025 - 12\u00ba Festival de Patchwork - Arte T\u00eaxtil","publisher":{"@id":"https:\/\/floripaquilt.com.br\/2025\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/floripaquilt.com.br\/2025\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/floripaquilt.com.br\/2025\/#organization","name":"Floripa Quilt","url":"https:\/\/floripaquilt.com.br\/2025\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/floripaquilt.com.br\/2025\/#\/schema\/logo\/image\/","url":"https:\/\/floripaquilt.com.br\/2025\/wp-content\/uploads\/2024\/08\/cropped-Sem-titulo-15.png","contentUrl":"https:\/\/floripaquilt.com.br\/2025\/wp-content\/uploads\/2024\/08\/cropped-Sem-titulo-15.png","width":3938,"height":669,"caption":"Floripa Quilt"},"image":{"@id":"https:\/\/floripaquilt.com.br\/2025\/#\/schema\/logo\/image\/"}}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/floripaquilt.com.br\/2025\/wp-json\/wp\/v2\/product\/10700","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/floripaquilt.com.br\/2025\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/floripaquilt.com.br\/2025\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/floripaquilt.com.br\/2025\/wp-json\/wp\/v2\/comments?post=10700"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/floripaquilt.com.br\/2025\/wp-json\/wp\/v2\/media\/10738"}],"wp:attachment":[{"href":"https:\/\/floripaquilt.com.br\/2025\/wp-json\/wp\/v2\/media?parent=10700"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/floripaquilt.com.br\/2025\/wp-json\/wp\/v2\/product_brand?post=10700"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/floripaquilt.com.br\/2025\/wp-json\/wp\/v2\/product_cat?post=10700"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/floripaquilt.com.br\/2025\/wp-json\/wp\/v2\/product_tag?post=10700"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}