{"id":5112,"date":"2020-01-04T11:56:51","date_gmt":"2020-01-04T14:56:51","guid":{"rendered":"https:\/\/floripaquilt.com.br\/2020\/?post_type=team&#038;p=5112"},"modified":"2023-02-21T17:13:13","modified_gmt":"2023-02-21T20:13:13","slug":"elis-marina-sehnem-engels","status":"publish","type":"team","link":"https:\/\/floripaquilt.com.br\/10anos\/prof\/elis-marina-sehnem-engels\/","title":{"rendered":"Elis Marina Sehnem Engels"},"content":{"rendered":"<p>Elis Marina Engels , natural de Tai\u00f3-SC \u00e9 professora de trabalhos manuais diversos em seu Ateli\u00ea Flor D&#8217;Elis desde 1994 (29anos). Em 2010 iniciou seus estudos na \u00e1rea de Patchwork participando de cursos com professores de renomes nacionais e internacionais . Em 2016 iniciou seus estudos mais avan\u00e7ados na \u00e1rea podendo assim criar e desenvolver seus pr\u00f3prios projetos. Ainda em 2016 j\u00e1 participou pela 1\u00b0vez de concurso e j\u00e1 recebendo premia\u00e7\u00e3o e desde ent\u00e3o foram:<br \/>\n2016 2\u00b0 lugar na categoria Estreante no Festival Internacional de Patchwork e Quilt de Gramado-RS com a obra &#8220;Lo Specchio della Stella&#8221;(o espelho da estrela)<br \/>\n2017 1\u00b0Lugar na categoria colchas no Festival Internacional de Patchwork e Quilt de Gramado-RS com a Obra &#8221; Fiori della Nonna&#8221; (Flores da vov\u00f3)<br \/>\n2018 men\u00e7\u00e3o honrosa no Festival Internacional de Patchwork e Quilt de Gramado-RS com a obra &#8220;Blumengarten&#8221; ( jardim de flores)<br \/>\n2019 1\u00b0Lugar na categoria colchas no Festival internacional de Patchwork e Quilt de Gramado-RS com a obra &#8221; Estrela guia &#8221;<br \/>\n2019 a Obra &#8221; Fiori dela Nonna &#8221; premiada em Gramado tamb\u00e9m foi selecionada para participar do concurso Internacional de Paducah-USA.<br \/>\nEntre outras participa\u00e7\u00f5es de exposi\u00e7\u00f5es de suas obras pelo Brasil.<br \/>\nParticipa pela 4\u00b0 vez como professora no Festival Floripa Quilt.<\/p>\n","protected":false},"author":29,"featured_media":7755,"menu_order":8,"template":"","team_designation":[],"team_department":[],"class_list":["post-5112","team","type-team","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Elis Marina Sehnem Engels - Floripa Quilt<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/floripaquilt.com.br\/10anos\/prof\/elis-marina-sehnem-engels\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Elis Marina Sehnem Engels - Floripa Quilt\" \/>\n<meta property=\"og:description\" content=\"Elis Marina Engels , natural de Tai\u00f3-SC \u00e9 professora de trabalhos manuais diversos em seu Ateli\u00ea Flor D&#8217;Elis desde 1994 (29anos). Em 2010 iniciou seus estudos na \u00e1rea de Patchwork participando de cursos com professores de renomes nacionais e internacionais . Em 2016 iniciou seus estudos mais avan\u00e7ados na \u00e1rea podendo assim criar e desenvolverLeia Mais\" \/>\n<meta property=\"og:url\" content=\"https:\/\/floripaquilt.com.br\/10anos\/prof\/elis-marina-sehnem-engels\/\" \/>\n<meta property=\"og:site_name\" content=\"Floripa Quilt\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-21T20:13:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/floripaquilt.com.br\/10anos\/wp-content\/uploads\/2023\/02\/Elis-Marina-Sehnem-Engels.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/floripaquilt.com.br\\\/10anos\\\/prof\\\/elis-marina-sehnem-engels\\\/\",\"url\":\"https:\\\/\\\/floripaquilt.com.br\\\/10anos\\\/prof\\\/elis-marina-sehnem-engels\\\/\",\"name\":\"Elis Marina Sehnem Engels - Floripa Quilt\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/floripaquilt.com.br\\\/10anos\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/floripaquilt.com.br\\\/10anos\\\/prof\\\/elis-marina-sehnem-engels\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/floripaquilt.com.br\\\/10anos\\\/prof\\\/elis-marina-sehnem-engels\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/floripaquilt.com.br\\\/10anos\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Elis-Marina-Sehnem-Engels.png\",\"datePublished\":\"2020-01-04T14:56:51+00:00\",\"dateModified\":\"2023-02-21T20:13:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/floripaquilt.com.br\\\/10anos\\\/prof\\\/elis-marina-sehnem-engels\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/floripaquilt.com.br\\\/10anos\\\/prof\\\/elis-marina-sehnem-engels\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/floripaquilt.com.br\\\/10anos\\\/prof\\\/elis-marina-sehnem-engels\\\/#primaryimage\",\"url\":\"https:\\\/\\\/floripaquilt.com.br\\\/10anos\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Elis-Marina-Sehnem-Engels.png\",\"contentUrl\":\"https:\\\/\\\/floripaquilt.com.br\\\/10anos\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Elis-Marina-Sehnem-Engels.png\",\"width\":1280,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/floripaquilt.com.br\\\/10anos\\\/prof\\\/elis-marina-sehnem-engels\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/floripaquilt.com.br\\\/10anos\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Elis Marina Sehnem Engels\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/floripaquilt.com.br\\\/10anos\\\/#website\",\"url\":\"https:\\\/\\\/floripaquilt.com.br\\\/10anos\\\/\",\"name\":\"Floripa Quilt\",\"description\":\"Floripa Quilt 2023 - 10\u00ba Festival de Patchwork e afins\",\"publisher\":{\"@id\":\"https:\\\/\\\/floripaquilt.com.br\\\/10anos\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/floripaquilt.com.br\\\/10anos\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/floripaquilt.com.br\\\/10anos\\\/#organization\",\"name\":\"Floripa Quilt\",\"url\":\"https:\\\/\\\/floripaquilt.com.br\\\/10anos\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/floripaquilt.com.br\\\/10anos\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/floripaquilt.com.br\\\/10anos\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/logo_page-0001-2-e1676201734326.jpg\",\"contentUrl\":\"https:\\\/\\\/floripaquilt.com.br\\\/10anos\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/logo_page-0001-2-e1676201734326.jpg\",\"width\":70,\"height\":55,\"caption\":\"Floripa Quilt\"},\"image\":{\"@id\":\"https:\\\/\\\/floripaquilt.com.br\\\/10anos\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Elis Marina Sehnem Engels - Floripa Quilt","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/floripaquilt.com.br\/10anos\/prof\/elis-marina-sehnem-engels\/","og_locale":"pt_BR","og_type":"article","og_title":"Elis Marina Sehnem Engels - Floripa Quilt","og_description":"Elis Marina Engels , natural de Tai\u00f3-SC \u00e9 professora de trabalhos manuais diversos em seu Ateli\u00ea Flor D&#8217;Elis desde 1994 (29anos). Em 2010 iniciou seus estudos na \u00e1rea de Patchwork participando de cursos com professores de renomes nacionais e internacionais . Em 2016 iniciou seus estudos mais avan\u00e7ados na \u00e1rea podendo assim criar e desenvolverLeia Mais","og_url":"https:\/\/floripaquilt.com.br\/10anos\/prof\/elis-marina-sehnem-engels\/","og_site_name":"Floripa Quilt","article_modified_time":"2023-02-21T20:13:13+00:00","og_image":[{"width":1280,"height":900,"url":"https:\/\/floripaquilt.com.br\/10anos\/wp-content\/uploads\/2023\/02\/Elis-Marina-Sehnem-Engels.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/floripaquilt.com.br\/10anos\/prof\/elis-marina-sehnem-engels\/","url":"https:\/\/floripaquilt.com.br\/10anos\/prof\/elis-marina-sehnem-engels\/","name":"Elis Marina Sehnem Engels - Floripa Quilt","isPartOf":{"@id":"https:\/\/floripaquilt.com.br\/10anos\/#website"},"primaryImageOfPage":{"@id":"https:\/\/floripaquilt.com.br\/10anos\/prof\/elis-marina-sehnem-engels\/#primaryimage"},"image":{"@id":"https:\/\/floripaquilt.com.br\/10anos\/prof\/elis-marina-sehnem-engels\/#primaryimage"},"thumbnailUrl":"https:\/\/floripaquilt.com.br\/10anos\/wp-content\/uploads\/2023\/02\/Elis-Marina-Sehnem-Engels.png","datePublished":"2020-01-04T14:56:51+00:00","dateModified":"2023-02-21T20:13:13+00:00","breadcrumb":{"@id":"https:\/\/floripaquilt.com.br\/10anos\/prof\/elis-marina-sehnem-engels\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/floripaquilt.com.br\/10anos\/prof\/elis-marina-sehnem-engels\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/floripaquilt.com.br\/10anos\/prof\/elis-marina-sehnem-engels\/#primaryimage","url":"https:\/\/floripaquilt.com.br\/10anos\/wp-content\/uploads\/2023\/02\/Elis-Marina-Sehnem-Engels.png","contentUrl":"https:\/\/floripaquilt.com.br\/10anos\/wp-content\/uploads\/2023\/02\/Elis-Marina-Sehnem-Engels.png","width":1280,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/floripaquilt.com.br\/10anos\/prof\/elis-marina-sehnem-engels\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/floripaquilt.com.br\/10anos\/"},{"@type":"ListItem","position":2,"name":"Elis Marina Sehnem Engels"}]},{"@type":"WebSite","@id":"https:\/\/floripaquilt.com.br\/10anos\/#website","url":"https:\/\/floripaquilt.com.br\/10anos\/","name":"Floripa Quilt","description":"Floripa Quilt 2023 - 10\u00ba Festival de Patchwork e afins","publisher":{"@id":"https:\/\/floripaquilt.com.br\/10anos\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/floripaquilt.com.br\/10anos\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/floripaquilt.com.br\/10anos\/#organization","name":"Floripa Quilt","url":"https:\/\/floripaquilt.com.br\/10anos\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/floripaquilt.com.br\/10anos\/#\/schema\/logo\/image\/","url":"https:\/\/floripaquilt.com.br\/10anos\/wp-content\/uploads\/2022\/11\/logo_page-0001-2-e1676201734326.jpg","contentUrl":"https:\/\/floripaquilt.com.br\/10anos\/wp-content\/uploads\/2022\/11\/logo_page-0001-2-e1676201734326.jpg","width":70,"height":55,"caption":"Floripa Quilt"},"image":{"@id":"https:\/\/floripaquilt.com.br\/10anos\/#\/schema\/logo\/image\/"}}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/floripaquilt.com.br\/10anos\/wp-json\/wp\/v2\/team\/5112","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/floripaquilt.com.br\/10anos\/wp-json\/wp\/v2\/team"}],"about":[{"href":"https:\/\/floripaquilt.com.br\/10anos\/wp-json\/wp\/v2\/types\/team"}],"author":[{"embeddable":true,"href":"https:\/\/floripaquilt.com.br\/10anos\/wp-json\/wp\/v2\/users\/29"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/floripaquilt.com.br\/10anos\/wp-json\/wp\/v2\/media\/7755"}],"wp:attachment":[{"href":"https:\/\/floripaquilt.com.br\/10anos\/wp-json\/wp\/v2\/media?parent=5112"}],"wp:term":[{"taxonomy":"team_designation","embeddable":true,"href":"https:\/\/floripaquilt.com.br\/10anos\/wp-json\/wp\/v2\/team_designation?post=5112"},{"taxonomy":"team_department","embeddable":true,"href":"https:\/\/floripaquilt.com.br\/10anos\/wp-json\/wp\/v2\/team_department?post=5112"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}