{"id":7090,"date":"2022-02-03T18:42:57","date_gmt":"2022-02-03T21:42:57","guid":{"rendered":"https:\/\/floripaquilt.com.br\/10anos\/?page_id=7090"},"modified":"2022-11-21T05:31:12","modified_gmt":"2022-11-21T08:31:12","slug":"concurso-de-boneco-a","status":"publish","type":"page","link":"https:\/\/floripaquilt.com.br\/10anos\/concurso-de-boneco-a\/","title":{"rendered":"Concurso de Bonecos(as) de Pano 2023"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>EDITAL 02\/2022<\/strong><\/h3>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>FLORIPA QUILT \u2013 Festival de Quilts e Patchwork<\/strong><\/h3>\n\n\n\n<h3 class=\"wp-block-heading\">CONCURSO DE BONECOS(AS) DE PANO AUTORAIS<\/h3>\n\n\n\n<p><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span style=\"text-decoration: underline;\">1- <strong>OBJETIVO:<\/strong><\/span><\/h3>\n\n\n\n<p>O presente edital tem o objetivo de apresentar e fornecer subs\u00eddios para a inscri\u00e7\u00e3o, participa\u00e7\u00e3o e premia\u00e7\u00e3o no Concurso de B<strong>onecos(as) de Pano <\/strong>do <strong>Floripa Quilt, <\/strong>que se realizar\u00e1 de <strong>3 a 6 de maio de 2023<\/strong>, em <strong>Florian\u00f3polis, Santa Catarina &#8211; Brasil<\/strong>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span style=\"text-decoration: underline;\">2- <strong>SOBRE O FLORIPA QUILT:<\/strong><\/span><\/h3>\n\n\n\n<p>Hoje, o Floripa Quilt \u00e9 sin\u00f4nimo de belas exposi\u00e7\u00f5es, cursos criativos, concursos e re\u00fane cada vez mais participantes gra\u00e7as \u00e0 boa energia que \u00e9 compartilhada durante o evento, todos os anos. Um sonho que virou realidade e foi costurado a muitas m\u00e3os.<\/p>\n\n\n\n<p>O Festival mobilizar\u00e1 em 2023 todo o segmento art\u00edstico e comercial que envolve a arte t\u00eaxtil, patchwork, quilts e artesanato regional, nacional e internacional; promover\u00e1 cursos, oficinas e aulas demonstrativas gratuitas; disponibilizar\u00e1 estandes com venda de materiais, produtos prontos, maquin\u00e1rios e ferramentas para o artesanato em geral; oferecer\u00e1 espa\u00e7os interativos aos participantes; proporcionar\u00e1 atividades solid\u00e1rias; servir\u00e1 como facilitador de rodas de conversas; estimular\u00e1 o iniciante \u00e0 arte de unir retalhos e ao reaproveitamento do res\u00edduo t\u00eaxtil; expor\u00e1 verdadeiras obras de artes de artistas renomados;&nbsp; premiar\u00e1 os melhores quilts do concurso e estrear\u00e1 nessa edi\u00e7\u00e3o, para comemorar os dez anos do evento, <strong>o Concurso de Bonecos(as) de Pano.<\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span style=\"text-decoration: underline;\">3 <strong>&#8211; DAS CATEGORIAS E MEDIDAS:<\/strong><\/span><\/h3>\n\n\n\n<p><strong>3.1<\/strong> \u2013 Categoria \u00danica: Boneco(a) de Pano Original&nbsp;&nbsp;<\/p>\n\n\n\n<p>Deve ser original e autoral com a expressividade do artista.<\/p>\n\n\n\n<p><strong>3.2<\/strong> \u2013 Tamanho:<\/p>\n\n\n\n<p>M\u00e1ximo de 100 cm.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span style=\"text-decoration: underline;\"><strong>4- DA PARTICIPA\u00c7\u00c3O:<\/strong><\/span><\/h3>\n\n\n\n<p><strong>4.1<\/strong> &#8211; Quem <strong>PODE<\/strong> participar:<\/p>\n\n\n\n<p>a) Qualquer pessoa maior de idade (18 anos), residente em <strong>territ\u00f3rio nacional ou internacional,<\/strong> apta a confeccionar um (a) Boneco (a) de Pano <strong>AUTORAL<\/strong>, e, desde que aceite as normas e observa\u00e7\u00f5es contidas neste regulamento;<\/p>\n\n\n\n<p><strong>4.2<\/strong> &#8211; Quem<strong> N\u00c3O<\/strong> <strong>PODE<\/strong> participar:<\/p>\n\n\n\n<p>a) Membros das Comiss\u00f5es: Julgadora e Organizadora;<\/p>\n\n\n\n<p>b) Pessoas f\u00edsicas que possuam rela\u00e7\u00f5es de parentesco com membros da Comiss\u00e3o Julgadora e\/ou Organizadora at\u00e9 o 3\u00ba grau;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span style=\"text-decoration: underline;\"><strong>5- DO CADASTRO E DA INSCRI\u00c7\u00c3O:<\/strong><\/span><\/h3>\n\n\n\n<p><strong>5.1<\/strong> &#8211; O candidato dever\u00e1 preencher a <strong><span style=\"text-decoration: underline;\"><a rel=\"noreferrer noopener\" href=\"https:\/\/forms.gle\/kMaxXgqKJ6ShSHKW8\" target=\"_blank\">ficha de inscri\u00e7\u00e3o<\/a><\/span><\/strong> on-line corretamente, <strong>at\u00e9 \u00e0s 18 horas do dia 10 de abril de 2023, <\/strong>anexando c\u00f3pia de documento de identifica\u00e7\u00e3o e comprovante do dep\u00f3sito;<\/p>\n\n\n\n<p><strong>5.2<\/strong> &#8211; O candidato poder\u00e1 inscrever mais de um(a) boneco(a), e para cada trabalho inscrito, dever\u00e1 ser preenchida uma nova <strong><span style=\"text-decoration: underline;\"><a href=\"https:\/\/forms.gle\/kMaxXgqKJ6ShSHKW8\" target=\"_blank\" rel=\"noreferrer noopener\">ficha de inscri\u00e7\u00e3o<\/a><\/span><\/strong>;<\/p>\n\n\n\n<p><strong>5.3<\/strong> &#8211; <strong>N\u00e3o <\/strong>ser\u00e3o aceitas inscri\u00e7\u00f5es de bonecos(as) que<strong> n\u00e3o sejam autorais,<\/strong> pois um dos principais crit\u00e9rios de avalia\u00e7\u00e3o \u00e9 a originalidade;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span style=\"text-decoration: underline;\"><strong>6- DO PROCESSO SELETIVO:<\/strong><\/span><\/h3>\n\n\n\n<p><strong>6.1<\/strong> &#8211; Sobre os bonecos(as):<\/p>\n\n\n\n<p>a) N\u00e3o ser\u00e3o aceitos bonecos(as) que n\u00e3o estejam dentro das normas regulamentares do presente <strong>EDITAL<\/strong>;<\/p>\n\n\n\n<p>b) O(A) boneco(a) dever\u00e1 ser feita a m\u00e3o e\/ou a m\u00e1quina, por\u00e9m de maneira artesanal;<\/p>\n\n\n\n<p>c)&nbsp;No(a) boneco(a) <strong>N\u00c3O<\/strong> dever\u00e1 conter o nome do(a) artista e nada que fa\u00e7a ser reconhecido(a) pela comiss\u00e3o julgadora;<\/p>\n\n\n\n<p>d) O (A) boneco (a) pode ser <strong>INDIVIDUAL<\/strong> (um autor), <strong>DUPLA<\/strong> (2 autores) OU <strong>GRUPO<\/strong> (3 ou mais), assim classificados em fun\u00e7\u00e3o do n\u00famero de pessoas que efetivamente confeccionaram a pe\u00e7a; A participa\u00e7\u00e3o de uma pessoa, por <strong>SERVI\u00c7O CONTRATADO OU COLABORATIVO<\/strong>, a torna <strong>CO-AUTORA<\/strong>, quer seja costurando, bordando, aplicando, pintando, colocando embelezamentos e\/ou acabamentos na pe\u00e7a;<\/p>\n\n\n\n<p>e) Os autores dos(as) bonecos(as) inscritos(as) cedem para a organiza\u00e7\u00e3o do evento, o direito de \u201cUso de Imagem\u201d dos mesmos por prazo indeterminado, para fins de divulga\u00e7\u00e3o. Em ambos os casos sempre ser\u00e3o citados o(a) autor(a) ou autores(as) e o nome do(a) boneco(a);<\/p>\n\n\n\n<p>f) <strong>Concomitantemente \u00e0 avalia\u00e7\u00e3o dos(as) bonecos(as), e de forma independente e soberana, a Comiss\u00e3o Organizadora escolher\u00e1 entre os trabalhos apresentados \u00e0 Comiss\u00e3o Julgadora<\/strong>, <strong><span style=\"text-decoration: underline;\">um(a) boneco(a) para ser o mascote do evento<\/span><\/strong> e o mesmo ficar\u00e1 sob dom\u00ednio do Floripa Quilt pelo tempo de 1 ano para o uso da imagem e divulga\u00e7\u00e3o da 11 \u00aa edi\u00e7\u00e3o, de modo gratuito, definitivo e irrevog\u00e1vel, sem restri\u00e7\u00e3o de frequ\u00eancia, sem que isto implique qualquer tipo de \u00f4nus ao Floripa Quilt. Para fins de divulga\u00e7\u00e3o em m\u00eddia eletr\u00f4nica e afins, o(a) boneco(a) escolhido como mascote poder\u00e1 ser transformado em AVATAR, e alguns tra\u00e7os originais poder\u00e3o ser alterados para uma melhor divulga\u00e7\u00e3o nos meios eletr\u00f4nicos e m\u00eddia impressa; O(A) boneco(a) escolhido como mascote, poder\u00e1 ser produzido em escala, em diversos tamanhos e tipos, para fins de divulga\u00e7\u00e3o e at\u00e9 mesmo de comercializa\u00e7\u00e3o, sendo que os valores advindos de vendas dessa produ\u00e7\u00e3o s\u00e3o de exclusividade do Floripa Quilt, sem quaisquer direito ao(s) autor(es);<\/p>\n\n\n\n<p>g) O trabalho escolhido pela Comiss\u00e3o Organizadora com o fim de ser o Mascote do Festival, dever\u00e1 ter a aquiesc\u00eancia do(a) autor(a) e ou autores(as) por escrito, observando o descrito no item anterior (\u201cf\u201d);<\/p>\n\n\n\n<p>h) Caso n\u00e3o haja a aquiesc\u00eancia por parte do autor do trabalho escolhido, a Comiss\u00e3o Organizadora optar\u00e1 por outra obra com a devida autoriza\u00e7\u00e3o.<\/p>\n\n\n\n<p>i) O trabalho escolhido para Mascote do Evento <strong>N\u00c3O \u00c9 SUPRIMIDO<\/strong> de participa\u00e7\u00e3o na avalia\u00e7\u00e3o do Concurso feito pela Comiss\u00e3o Julgadora, podendo o mesmo tamb\u00e9m ser premiado se fizer jus aos crit\u00e9rios de julgamento dos jurados.<\/p>\n\n\n\n<p><strong>6.2<\/strong> &#8211; Sobre os Jurados:<\/p>\n\n\n\n<p>a) A escolha dos ju\u00edzes \u00e9 de responsabilidade <strong>exclusiva da organiza\u00e7\u00e3o do evento<\/strong>.<\/p>\n\n\n\n<p>b) Ser\u00e3o escolhidos pela Comiss\u00e3o Julgadora, os <strong>1\u00b0, 2\u00b0 e 3\u00ba lugares do Concurso<\/strong>, desde que os(as) bonecos(as) tenham qualidade para tal;<\/p>\n\n\n\n<p>c) Os (As) bonecos (as) ser\u00e3o avaliados pela originalidade, conceito\/proposta do candidato, apar\u00eancia, impacto visual, design, efeito da expressividade, t\u00e9cnicas especiais, complexidade, qualidade e acabamentos;<\/p>\n\n\n\n<p>d) A decis\u00e3o dos jurados \u00e9 soberana e n\u00e3o caber\u00e1 qualquer tipo de contesta\u00e7\u00e3o ou recurso por parte dos participantes.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span style=\"text-decoration: underline;\"><strong>7<\/strong>&#8211; <strong>DAS RESPONSABILIDADES:<\/strong><\/span><\/h3>\n\n\n\n<p><strong>7.1<\/strong> &#8211; Sobre a inscri\u00e7\u00e3o:<\/p>\n\n\n\n<p>a) O candidato (a) dever\u00e1 preencher a <strong><span style=\"text-decoration: underline;\"><a href=\"https:\/\/forms.gle\/kMaxXgqKJ6ShSHKW8\" target=\"_blank\" rel=\"noreferrer noopener\">ficha de inscri\u00e7\u00e3o<\/a><\/span><\/strong> com todos os campos completos;<\/p>\n\n\n\n<p>b) Ser\u00e1 cobrada uma taxa de servi\u00e7os no valor de R$ 100,00 (cem reais);<\/p>\n\n\n\n<p>c) O pagamento da taxa dever\u00e1 ser feito mediante dep\u00f3sito banc\u00e1rio (TED ou PIX), na conta de<\/p>\n\n\n\n<blockquote class=\"wp-block-quote has-text-align-center is-layout-flow wp-block-quote-is-layout-flow\"><p><strong>Jana\u00edna Machado Cordeiro<\/strong><\/p><p><strong>CNPJ n\u00ba 97.532.358\/0001-05<\/strong><\/p><p><strong>Banco Ita\u00fa &#8211; 341<\/strong><\/p><p><strong>Ag\u00eancia 8668<\/strong><\/p><p><strong>Conta Corrente 24.304-4<\/strong><\/p><p><strong>CHAVE PIX: 97.532.358\/0001-05<\/strong><\/p><\/blockquote>\n\n\n\n<p><strong>7.2<\/strong> \u2013 Sobre o Envio:<\/p>\n\n\n\n<p>a) Enviar c\u00f3pia do comprovante de pagamento quando do preenchimento da <strong><span style=\"text-decoration: underline;\"><a href=\"https:\/\/forms.gle\/kMaxXgqKJ6ShSHKW8\" target=\"_blank\" rel=\"noreferrer noopener\">ficha de inscri\u00e7\u00e3o<\/a><\/span><\/strong>;<\/p>\n\n\n\n<p>b) Os (As) bonecos (as) inscritas no Concurso dever\u00e3o ser enviadas at\u00e9 o dia 10 de abril de 2023, valendo a data de postagem do correio, para o endere\u00e7o:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote has-text-align-center is-layout-flow wp-block-quote-is-layout-flow\"><p><strong>Jana\u00edna Machado Cordeiro<\/strong><\/p><p><strong>FLORIPA QUILT \u2013<\/strong><\/p><p><strong>RUA DANIEL PETRY, 460<\/strong><\/p><p><strong>CENTRO \u2013 ANT\u00d4NIO CARLOS \u2013 SC<\/strong><\/p><p><strong>CEP 88.180-000<\/strong><\/p><\/blockquote>\n\n\n\n<p>c) <strong>As pe\u00e7as postadas ap\u00f3s 10 de abril de 2023, estar\u00e3o automaticamente desclassificadas;<\/strong><\/p>\n\n\n\n<p>d) Caso o artista opte por n\u00e3o usar o servi\u00e7o de postagem dos Correios<strong>, o trabalho dever\u00e1 ser entregue pessoalmente no dia 07 (sexta-feira) de abril de 2023, das 14 as 18 horas, no seguinte endere\u00e7o:<\/strong><\/p>\n\n\n\n<blockquote class=\"wp-block-quote has-text-align-center is-layout-flow wp-block-quote-is-layout-flow\"><p><strong>CENTRO DE EVENTOS SESC CACUP\u00c9<\/strong><\/p><p><strong>A\/C JANA\u00cdNA MACHADO CORDEIRO<\/strong><\/p><p><strong>ESTRADA HAROLDO SOARES GLAVAN, 1870<\/strong><\/p><p><strong>CACUP\u00c9 &#8211; FLORIAN\u00d3POLIS \u2013 SC<\/strong><\/p><\/blockquote>\n\n\n\n<p>e) Optando pela entrega presencial, o procedimento de inscri\u00e7\u00e3o permanece o mesmo, ou seja, on-line conforme item 5.1;<\/p>\n\n\n\n<p>f) O(A) boneco(a) deve ser acondicionado dentro de uma embalagem de tamanho adequado, em caixa ou saco em tecido com fechamento e com uma etiqueta com os SEGUINTES dados: &nbsp;<\/p>\n\n\n\n<blockquote class=\"wp-block-quote has-text-align-center is-layout-flow wp-block-quote-is-layout-flow\"><p><strong>Nome da pe\u00e7a (escrito com letras maiores para destacar)<\/strong><\/p><p><strong>Nome dos autor(es);<\/strong><\/p><p><strong>Endere\u00e7o completo do autor que inscreveu a pe\u00e7a;<\/strong><\/p><p><strong>Telefone celular com DDD e WhatsApp;<\/strong><\/p><p><strong>Ano de conclus\u00e3o da pe\u00e7a.<\/strong><\/p><\/blockquote>\n\n\n\n<p><strong>7.3<\/strong> &#8211; Retirada dos(das) Bonecos(as):<\/p>\n\n\n\n<p>a) Os(As) bonecos(as) s\u00f3 poder\u00e3o ser retirados ap\u00f3s o final da exposi\u00e7\u00e3o, no dia 06\/05\/2023, no hor\u00e1rio entre 18:30 horas e 20 horas, sem qualquer exce\u00e7\u00e3o. <\/p>\n\n\n\n<p>b) Os (As) bonecos (as) n\u00e3o retiradas no dia e hor\u00e1rio previsto ser\u00e3o devolvidas <strong>via Sedex a cobrar<\/strong> em at\u00e9 50 dias a partir da data de encerramento da exposi\u00e7\u00e3o. Todas as despesas com correio s\u00e3o de responsabilidades do autor.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span style=\"text-decoration: underline;\"><strong>8- DO FESTIVAL<\/strong>:<\/span><\/h3>\n\n\n\n<p><strong>8.1<\/strong> &#8211; A organiza\u00e7\u00e3o do evento manter\u00e1 no local da exposi\u00e7\u00e3o uma pessoa qualificada para das informa\u00e7\u00f5es sobre o concurso, isentando-se da responsabilidade por perdas e danos de qualquer tipo;<\/p>\n\n\n\n<p><strong>8.2<\/strong> &#8211; A montagem da exposi\u00e7\u00e3o \u00e9 de responsabilidade da organiza\u00e7\u00e3o do evento;<\/p>\n\n\n\n<p><strong>8.3<\/strong> &#8211; Os(As) bonecos(as) expostas n\u00e3o ser\u00e3o cobertas por seguro.<\/p>\n\n\n\n<p><strong>8.4<\/strong> &#8211; Caso n\u00e3o haja inscri\u00e7\u00f5es suficientes, a organiza\u00e7\u00e3o optar\u00e1 pela suspens\u00e3o da categoria.<\/p>\n\n\n\n<p><strong>8.5<\/strong> &#8211; A Comiss\u00e3o Julgadora \u00e9 <strong>SOBERANA<\/strong> e sua composi\u00e7\u00e3o \u00e9 de responsabilidade exclusiva da organiza\u00e7\u00e3o do Festival;<\/p>\n\n\n\n<p><strong>8.6<\/strong> &#8211; Crit\u00e9rios de desempate ser\u00e3o definidos pela Comiss\u00e3o Julgadora do evento;<\/p>\n\n\n\n<p><strong>8.7<\/strong> &#8211; O autor ou autores das pe\u00e7as premiadas ser\u00e3o notificados ao t\u00e9rmino do julgamento.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span style=\"text-decoration: underline;\"><strong>9- DA PREMIA\u00c7\u00c3O:<\/strong><\/span><\/h3>\n\n\n\n<p><strong>9.1<\/strong> &#8211; Todos os participantes receber\u00e3o diplomas de participa\u00e7\u00e3o;<\/p>\n\n\n\n<p><strong>9.2<\/strong> &#8211; Os <strong>2\u00ba e 3\u00ba lugares<\/strong> receber\u00e3o um presente especial;<\/p>\n\n\n\n<p><strong>9.3<\/strong> &#8211; O <strong>1\u00ba lugar<\/strong> receber\u00e1 em esp\u00e9cie, <strong>hum<\/strong> <strong>mil reais<\/strong> (R$ 1.000,00).<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span style=\"text-decoration: underline;\"><strong>10- DISPOSI\u00c7\u00d5ES FINAIS:<\/strong><\/span><\/h3>\n\n\n\n<p><strong>10.1<\/strong> \u2013 A pe\u00e7a dever\u00e1 <strong>ser postada<\/strong> at\u00e9 o dia <strong>10 (segunda-feira) de abril de 2023<\/strong> ou entregue pessoalmente no dia <strong>07 (sexta-feira) de abril de 2023<\/strong>, das 14 as 18 horas;<\/p>\n\n\n\n<p><strong>10.2<\/strong> \u2013 O <strong>julgamento<\/strong> anteceder\u00e1 ao dia <strong>03 (quarta-feira) de maio de 2023<\/strong> (data de abertura do festival);<\/p>\n\n\n\n<p><strong>10.3<\/strong> \u2013 A cerim\u00f4nia de premia\u00e7\u00e3o ser\u00e1 dia <strong>03 (quarta-feira) de maio<\/strong> <strong>de 2023<\/strong>, <strong>as 11 horas<\/strong>, <strong>no SESC<\/strong> <strong>Cacup\u00e9<\/strong>.<\/p>\n\n\n\n<p><strong>10.4<\/strong> \u2013 A exposi\u00e7\u00e3o do Concurso de Bonecos(as) \u00e9 aberta ao p\u00fablico de <strong>03 (quarta-feira) a 06 de maio (s\u00e1bado) de 2023, das 12 as 18 horas<\/strong>;<\/p>\n\n\n\n<p><strong>10.5<\/strong> \u2013 A <strong>retirada<\/strong> das pe\u00e7as s\u00f3 poder\u00e1 ser feita no dia <strong>06 (s\u00e1bado) de maio de 2023, a partir das 18h30, at\u00e9 as 20h,<\/strong> pelo respons\u00e1vel da inscri\u00e7\u00e3o ou por ele delegada (por escrito) e entregue a secretaria do evento para identifica\u00e7\u00e3o e recebimento da pe\u00e7a. As pe\u00e7as n\u00e3o retiradas dessa forma ser\u00e3o devolvidas por correio em at\u00e9 40 dias ap\u00f3s o t\u00e9rmino do Festival.<\/p>\n\n\n\n<p><strong>10.6<\/strong> &#8211; <strong>A Comiss\u00e3o Organizadora disponibiliza um canal para d\u00favidas, <a href=\"mailto:fqbonecos@gmail.com\" target=\"_blank\" rel=\"noreferrer noopener\">fqbonecos@gmail.com<\/a>, onde o autor poder\u00e1 esclarecer qualquer&nbsp;ponto que n\u00e3o esteja claro neste edital. Somente por esse canal ser\u00e3o dirimidas as d\u00favidas que se apresentarem.<\/strong><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-text-align-center\">Florian\u00f3polis, 20 de novembro de 2022.<\/p>\n\n\n\n<p class=\"has-text-align-center\"><strong>Jana\u00edna Machado Cordeiro<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center\"><strong>Organizadora<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>EDITAL 02\/2022 FLORIPA QUILT \u2013 Festival de Quilts e Patchwork CONCURSO DE BONECOS(AS) DE PANO AUTORAIS 1- OBJETIVO: O presente edital tem o objetivo de apresentar e fornecer subs\u00eddios para a inscri\u00e7\u00e3o, participa\u00e7\u00e3o e premia\u00e7\u00e3o no Concurso de Bonecos(as) de Pano do Floripa Quilt, que se realizar\u00e1 de 3 a 6 de maio de 2023,<\/p>\n<div><a class=\"btn-filled btn\" href=\"https:\/\/floripaquilt.com.br\/10anos\/concurso-de-boneco-a\/\" title=\"Concurso de Bonecos(as) de Pano 2023\">Leia Mais<\/a><\/div>\n","protected":false},"author":29,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-templates\/no-sidebar.php","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-7090","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Concurso de Bonecos(as) de Pano 2023 - Floripa Quilt<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/floripaquilt.com.br\/10anos\/concurso-de-boneco-a\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Concurso de Bonecos(as) de Pano 2023 - Floripa Quilt\" \/>\n<meta property=\"og:description\" content=\"EDITAL 02\/2022 FLORIPA QUILT \u2013 Festival de Quilts e Patchwork CONCURSO DE BONECOS(AS) DE PANO AUTORAIS 1- OBJETIVO: O presente edital tem o objetivo de apresentar e fornecer subs\u00eddios para a inscri\u00e7\u00e3o, participa\u00e7\u00e3o e premia\u00e7\u00e3o no Concurso de Bonecos(as) de Pano do Floripa Quilt, que se realizar\u00e1 de 3 a 6 de maio de 2023,Leia Mais\" \/>\n<meta property=\"og:url\" content=\"https:\/\/floripaquilt.com.br\/10anos\/concurso-de-boneco-a\/\" \/>\n<meta property=\"og:site_name\" content=\"Floripa Quilt\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-21T08:31:12+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/floripaquilt.com.br\\\/10anos\\\/concurso-de-boneco-a\\\/\",\"url\":\"https:\\\/\\\/floripaquilt.com.br\\\/10anos\\\/concurso-de-boneco-a\\\/\",\"name\":\"Concurso de Bonecos(as) de Pano 2023 - Floripa Quilt\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/floripaquilt.com.br\\\/10anos\\\/#website\"},\"datePublished\":\"2022-02-03T21:42:57+00:00\",\"dateModified\":\"2022-11-21T08:31:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/floripaquilt.com.br\\\/10anos\\\/concurso-de-boneco-a\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/floripaquilt.com.br\\\/10anos\\\/concurso-de-boneco-a\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/floripaquilt.com.br\\\/10anos\\\/concurso-de-boneco-a\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/floripaquilt.com.br\\\/10anos\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Concurso de Bonecos(as) de Pano 2023\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/floripaquilt.com.br\\\/10anos\\\/#website\",\"url\":\"https:\\\/\\\/floripaquilt.com.br\\\/10anos\\\/\",\"name\":\"Floripa Quilt\",\"description\":\"Floripa Quilt 2023 - 10\u00ba Festival de Patchwork e afins\",\"publisher\":{\"@id\":\"https:\\\/\\\/floripaquilt.com.br\\\/10anos\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/floripaquilt.com.br\\\/10anos\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/floripaquilt.com.br\\\/10anos\\\/#organization\",\"name\":\"Floripa Quilt\",\"url\":\"https:\\\/\\\/floripaquilt.com.br\\\/10anos\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/floripaquilt.com.br\\\/10anos\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/floripaquilt.com.br\\\/10anos\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/logo_page-0001-2-e1676201734326.jpg\",\"contentUrl\":\"https:\\\/\\\/floripaquilt.com.br\\\/10anos\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/logo_page-0001-2-e1676201734326.jpg\",\"width\":70,\"height\":55,\"caption\":\"Floripa Quilt\"},\"image\":{\"@id\":\"https:\\\/\\\/floripaquilt.com.br\\\/10anos\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Concurso de Bonecos(as) de Pano 2023 - Floripa Quilt","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/floripaquilt.com.br\/10anos\/concurso-de-boneco-a\/","og_locale":"pt_BR","og_type":"article","og_title":"Concurso de Bonecos(as) de Pano 2023 - Floripa Quilt","og_description":"EDITAL 02\/2022 FLORIPA QUILT \u2013 Festival de Quilts e Patchwork CONCURSO DE BONECOS(AS) DE PANO AUTORAIS 1- OBJETIVO: O presente edital tem o objetivo de apresentar e fornecer subs\u00eddios para a inscri\u00e7\u00e3o, participa\u00e7\u00e3o e premia\u00e7\u00e3o no Concurso de Bonecos(as) de Pano do Floripa Quilt, que se realizar\u00e1 de 3 a 6 de maio de 2023,Leia Mais","og_url":"https:\/\/floripaquilt.com.br\/10anos\/concurso-de-boneco-a\/","og_site_name":"Floripa Quilt","article_modified_time":"2022-11-21T08:31:12+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. tempo de leitura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/floripaquilt.com.br\/10anos\/concurso-de-boneco-a\/","url":"https:\/\/floripaquilt.com.br\/10anos\/concurso-de-boneco-a\/","name":"Concurso de Bonecos(as) de Pano 2023 - Floripa Quilt","isPartOf":{"@id":"https:\/\/floripaquilt.com.br\/10anos\/#website"},"datePublished":"2022-02-03T21:42:57+00:00","dateModified":"2022-11-21T08:31:12+00:00","breadcrumb":{"@id":"https:\/\/floripaquilt.com.br\/10anos\/concurso-de-boneco-a\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/floripaquilt.com.br\/10anos\/concurso-de-boneco-a\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/floripaquilt.com.br\/10anos\/concurso-de-boneco-a\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/floripaquilt.com.br\/10anos\/"},{"@type":"ListItem","position":2,"name":"Concurso de Bonecos(as) de Pano 2023"}]},{"@type":"WebSite","@id":"https:\/\/floripaquilt.com.br\/10anos\/#website","url":"https:\/\/floripaquilt.com.br\/10anos\/","name":"Floripa Quilt","description":"Floripa Quilt 2023 - 10\u00ba Festival de Patchwork e afins","publisher":{"@id":"https:\/\/floripaquilt.com.br\/10anos\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/floripaquilt.com.br\/10anos\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/floripaquilt.com.br\/10anos\/#organization","name":"Floripa Quilt","url":"https:\/\/floripaquilt.com.br\/10anos\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/floripaquilt.com.br\/10anos\/#\/schema\/logo\/image\/","url":"https:\/\/floripaquilt.com.br\/10anos\/wp-content\/uploads\/2022\/11\/logo_page-0001-2-e1676201734326.jpg","contentUrl":"https:\/\/floripaquilt.com.br\/10anos\/wp-content\/uploads\/2022\/11\/logo_page-0001-2-e1676201734326.jpg","width":70,"height":55,"caption":"Floripa Quilt"},"image":{"@id":"https:\/\/floripaquilt.com.br\/10anos\/#\/schema\/logo\/image\/"}}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/floripaquilt.com.br\/10anos\/wp-json\/wp\/v2\/pages\/7090","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/floripaquilt.com.br\/10anos\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/floripaquilt.com.br\/10anos\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/floripaquilt.com.br\/10anos\/wp-json\/wp\/v2\/users\/29"}],"replies":[{"embeddable":true,"href":"https:\/\/floripaquilt.com.br\/10anos\/wp-json\/wp\/v2\/comments?post=7090"}],"version-history":[{"count":35,"href":"https:\/\/floripaquilt.com.br\/10anos\/wp-json\/wp\/v2\/pages\/7090\/revisions"}],"predecessor-version":[{"id":7718,"href":"https:\/\/floripaquilt.com.br\/10anos\/wp-json\/wp\/v2\/pages\/7090\/revisions\/7718"}],"wp:attachment":[{"href":"https:\/\/floripaquilt.com.br\/10anos\/wp-json\/wp\/v2\/media?parent=7090"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}