{"id":156,"date":"2007-09-04T10:48:10","date_gmt":"2007-09-04T17:48:10","guid":{"rendered":"http:\/\/wpthemetestdata.wordpress.com\/page-with-comments-disabled\/"},"modified":"2023-04-23T20:44:31","modified_gmt":"2023-04-23T23:44:31","slug":"sobre","status":"publish","type":"page","link":"https:\/\/floripaquilt.com.br\/10anos\/sobre\/","title":{"rendered":"10 Anos Floripa Quilt"},"content":{"rendered":"\n<figure class=\"wp-block-gallery alignleft has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" data-id=\"7\" src=\"https:\/\/floripaquilt.com.br\/10anos\/wp-content\/uploads\/2016\/10\/cropped-logo512px.png\" alt=\"\" class=\"wp-image-7\" srcset=\"https:\/\/floripaquilt.com.br\/10anos\/wp-content\/uploads\/2016\/10\/cropped-logo512px.png 512w, https:\/\/floripaquilt.com.br\/10anos\/wp-content\/uploads\/2016\/10\/cropped-logo512px-150x150.png 150w, https:\/\/floripaquilt.com.br\/10anos\/wp-content\/uploads\/2016\/10\/cropped-logo512px-300x300.png 300w, https:\/\/floripaquilt.com.br\/10anos\/wp-content\/uploads\/2016\/10\/cropped-logo512px-270x270.png 270w, https:\/\/floripaquilt.com.br\/10anos\/wp-content\/uploads\/2016\/10\/cropped-logo512px-192x192.png 192w, https:\/\/floripaquilt.com.br\/10anos\/wp-content\/uploads\/2016\/10\/cropped-logo512px-180x180.png 180w, https:\/\/floripaquilt.com.br\/10anos\/wp-content\/uploads\/2016\/10\/cropped-logo512px-32x32.png 32w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/figure>\n<\/figure>\n\n\n<p>\u00a0<\/p>\n<p>Um brinde aos 10 anos Floripa Quilt. Um caminho orientado pelo empenho, paix\u00e3o, \u00e9tica e profissionalismo.<\/p>\n<p>Dez anos de Floripa Quilt e o percurso at\u00e9 aqui, \u00e9 mesmo para comemorar. A maior feira de patchwork de Santa Catarina\u00a0 mobiliza todo o segmento art\u00edstico e comercial que envolve a arte de unir retalhos, divulga trabalhos locais, nacionais e internacionais, promove oficinas de aprimoramento de t\u00e9cnicas, disponibiliza estandes com venda de materiais destinados \u00e0 arte do patchwork, traz aos nossos olhos e sentidos, atrav\u00e9s de suas exposi\u00e7\u00f5es e mostras, belas obras t\u00eaxteis e ainda oferece \u00e0 voc\u00ea, a oportunidade de materializar seu talento art\u00edstico, atrav\u00e9s do Concurso de Quilts.<\/p>\n<p>Um anivers\u00e1rio especial&#8230; muitas novidades. Concurso de Bonecas, aulas demonstrativas gratuitas, rodas de conversas, palestras, apresenta\u00e7\u00f5es folcl\u00f3ricas e muito mais. Essas novidades refletem um reposicionamento e uma outra abordagem da <strong>ARTE-ARTESANATO<\/strong> neste momento de grandes mudan\u00e7as e desafios.<\/p>\n<p>&#8220;Queremos ampliar o p\u00fablico, mostrar para o pr\u00f3prio mercado que a arte feita com agulhas vai muito al\u00e9m do repert\u00f3rio tradicional, e possibilitar uma compreens\u00e3o mais ampla e contempor\u00e2nea sobre o patchwork e o quilt.&#8221; (Jana\u00edna Machado Cordeiro)\u00a0<\/p>\n<p class=\"p1\">\u00c9 assim que pretendemos assinalar os nossos 10 anos de Floripa Quilt!<\/p>\n<hr \/>\n<h4 class=\"p1\">Como tudo come\u00e7ou<\/h4>\n<p class=\"p1\">Foi em um pequeno ateli\u00ea de Patchwork que o sonho de Jana\u00edna Machado Cordeiro come\u00e7ou a ganhar forma. Entre uma feira e outra que visitava, a artes\u00e3 viu a possibilidade de trazer para Florian\u00f3polis um festival que unisse cursos, expositores e admiradores dessa arte, al\u00e9m de valorizar a cultura de Santa Catarina. Come\u00e7ou a conquistar parcerias com pessoas que tamb\u00e9m acreditavam nesse sonho e o evento n\u00e3o parou mais de crescer. Hoje, o Floripa Quilt \u00e9 sin\u00f4nimo de belas exposi\u00e7\u00f5es, cursos criativos, concursos e re\u00fane cada vez mais participantes gra\u00e7as \u00e0 energia boa que \u00e9 compartilhada durante o evento, todos os anos. Um sonho que virou realidade e foi costurado a muitas m\u00e3os.<\/p>\n<hr \/>\n<h4 class=\"p1\">Informa\u00e7\u00f5es<\/h4>\n<p>A capital catarinense sediar\u00e1, entre os dias <strong>03 a 06 de maio de 2023<\/strong>, o 10\u00ba Floripa Quilt. O evento ser\u00e1 realizado no Centro de Eventos do Hotel SESC Cacup\u00e9, sito a Estrada Haroldo Soares Glavan, n\u00ba 1670, Cacup\u00e9, Florian\u00f3polis\/SC. Como de costume, o evento vai oferecer uma vasta programa\u00e7\u00e3o com o objetivo de promover o interc\u00e2mbio de t\u00e9cnicas da arte em tecido, com a participa\u00e7\u00e3o de convidados de renome nacional e internacional, valorizando o trabalho manual e inovando com a inser\u00e7\u00e3o de valores culturais regionais no universo do <em>patchwork<\/em>.<\/p>\n<p>Como nas edi\u00e7\u00f5es anteriores, o p\u00fablico em geral poder\u00e1 visitar os estandes, adquirir produtos, al\u00e9m de acompanhar diversas exposi\u00e7\u00f5es, das 12 \u00e0s 18h, de quarta \u00e0 s\u00e1bado. A entrada custar\u00e1 apenas R$ 10,00 por dia (inteira) e R$ 5,00 (meia).<\/p>\n<p>Enfim, trata-se de um grande evento e podemos assegurar de que \u00e9 o maior festival de patchwork do estado e um dos mais aguardados do Brasil.<\/p>\n<hr \/>\n<h4 class=\"p1\">Servi\u00e7os<\/h4>\n<p><strong>Onde: <\/strong>SESC Cacup\u00e9 &#8211; Estrada Haroldo Soares Glavan, 1670 &#8211; Cacup\u00e9 &#8211; Fpolis\/SC<\/p>\n<p><strong>Data: <\/strong>3 a 6 de maio (quarta \u00e0 s\u00e1bado)<\/p>\n<p><strong>Hor\u00e1rio: <\/strong>12h \u00e0s 18h \u00a0<\/p>\n<p><strong>Entrada:\u00a0 <\/strong>R$ 10,00 inteira e R$ 5,00 meia\u00a0<\/p>\n<p><strong>Caravanas<\/strong>: com 15 ou mais participantes, cadastradas previamente ter\u00e3o acesso gratuito.<\/p>\n<p><strong>Estacionamento: <\/strong>R$10,00 a di\u00e1ria<\/p>\n<h4><strong>Hospedagem:<\/strong> <a href=\"https:\/\/sesc-sc.com.br\/hotel-sesc-em-cacupe\/reservas-no-hotel-sesc-cacupe-em-florianopolis\" target=\"_blank\" rel=\"noopener\"><strong>Hotel Sesc Cacup\u00e9<\/strong><\/a><\/h4>\n<p><strong>*Pre\u00e7o de comerci\u00e1rio (<\/strong><strong>comunicar que a hospedagem \u00e9 em virtude do evento)<\/strong><\/p>\n<p><strong>Restaurante:<\/strong> 11h at\u00e9 14h (almo\u00e7o) \/ 19h at\u00e9 21h (jantar)<\/p>\n<p><strong>Lanchonete<\/strong>: 10h at\u00e9 18h<\/p>\n<p><strong>Cafeteria<\/strong>: 14h at\u00e9 18h, no Sal\u00e3o Campeche &#8211; Sesc<\/p>\n<hr \/>\n<p><strong>Aguardamos por voc\u00ea!!!!!!<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>Jana\u00edna Machado Cordeiro<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>Organizadora<\/strong><\/p>\n<h4>\u00a0<\/h4>","protected":false},"excerpt":{"rendered":"<p>\u00a0 Um brinde aos 10 anos Floripa Quilt. Um caminho orientado pelo empenho, paix\u00e3o, \u00e9tica e profissionalismo. Dez anos de Floripa Quilt e o percurso at\u00e9 aqui, \u00e9 mesmo para comemorar. A maior feira de patchwork de Santa Catarina\u00a0 mobiliza todo o segmento art\u00edstico e comercial que envolve a arte de unir retalhos, divulga trabalhos<\/p>\n<div><a class=\"btn-filled btn\" href=\"https:\/\/floripaquilt.com.br\/10anos\/sobre\/\" title=\"10 Anos Floripa Quilt\">Leia Mais<\/a><\/div>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":4,"comment_status":"closed","ping_status":"closed","template":"page-templates\/no-sidebar.php","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-156","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>10 Anos Floripa Quilt - Floripa Quilt<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/floripaquilt.com.br\/10anos\/sobre\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"10 Anos Floripa Quilt - Floripa Quilt\" \/>\n<meta property=\"og:description\" content=\"\u00a0 Um brinde aos 10 anos Floripa Quilt. Um caminho orientado pelo empenho, paix\u00e3o, \u00e9tica e profissionalismo. Dez anos de Floripa Quilt e o percurso at\u00e9 aqui, \u00e9 mesmo para comemorar. A maior feira de patchwork de Santa Catarina\u00a0 mobiliza todo o segmento art\u00edstico e comercial que envolve a arte de unir retalhos, divulga trabalhosLeia Mais\" \/>\n<meta property=\"og:url\" content=\"https:\/\/floripaquilt.com.br\/10anos\/sobre\/\" \/>\n<meta property=\"og:site_name\" content=\"Floripa Quilt\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-23T23:44:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/floripaquilt.com.br\/10anos\/wp-content\/uploads\/2016\/10\/cropped-logo512px.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/floripaquilt.com.br\\\/10anos\\\/sobre\\\/\",\"url\":\"https:\\\/\\\/floripaquilt.com.br\\\/10anos\\\/sobre\\\/\",\"name\":\"10 Anos Floripa Quilt - Floripa Quilt\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/floripaquilt.com.br\\\/10anos\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/floripaquilt.com.br\\\/10anos\\\/sobre\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/floripaquilt.com.br\\\/10anos\\\/sobre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/floripaquilt.com.br\\\/10anos\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/cropped-logo512px.png\",\"datePublished\":\"2007-09-04T17:48:10+00:00\",\"dateModified\":\"2023-04-23T23:44:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/floripaquilt.com.br\\\/10anos\\\/sobre\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/floripaquilt.com.br\\\/10anos\\\/sobre\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/floripaquilt.com.br\\\/10anos\\\/sobre\\\/#primaryimage\",\"url\":\"https:\\\/\\\/floripaquilt.com.br\\\/10anos\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/cropped-logo512px.png\",\"contentUrl\":\"https:\\\/\\\/floripaquilt.com.br\\\/10anos\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/cropped-logo512px.png\",\"width\":512,\"height\":512},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/floripaquilt.com.br\\\/10anos\\\/sobre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/floripaquilt.com.br\\\/10anos\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"10 Anos Floripa Quilt\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/floripaquilt.com.br\\\/10anos\\\/#website\",\"url\":\"https:\\\/\\\/floripaquilt.com.br\\\/10anos\\\/\",\"name\":\"Floripa Quilt\",\"description\":\"Floripa Quilt 2023 - 10\u00ba Festival de Patchwork e afins\",\"publisher\":{\"@id\":\"https:\\\/\\\/floripaquilt.com.br\\\/10anos\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/floripaquilt.com.br\\\/10anos\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/floripaquilt.com.br\\\/10anos\\\/#organization\",\"name\":\"Floripa Quilt\",\"url\":\"https:\\\/\\\/floripaquilt.com.br\\\/10anos\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/floripaquilt.com.br\\\/10anos\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/floripaquilt.com.br\\\/10anos\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/logo_page-0001-2-e1676201734326.jpg\",\"contentUrl\":\"https:\\\/\\\/floripaquilt.com.br\\\/10anos\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/logo_page-0001-2-e1676201734326.jpg\",\"width\":70,\"height\":55,\"caption\":\"Floripa Quilt\"},\"image\":{\"@id\":\"https:\\\/\\\/floripaquilt.com.br\\\/10anos\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"10 Anos Floripa Quilt - Floripa Quilt","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/floripaquilt.com.br\/10anos\/sobre\/","og_locale":"pt_BR","og_type":"article","og_title":"10 Anos Floripa Quilt - Floripa Quilt","og_description":"\u00a0 Um brinde aos 10 anos Floripa Quilt. Um caminho orientado pelo empenho, paix\u00e3o, \u00e9tica e profissionalismo. Dez anos de Floripa Quilt e o percurso at\u00e9 aqui, \u00e9 mesmo para comemorar. A maior feira de patchwork de Santa Catarina\u00a0 mobiliza todo o segmento art\u00edstico e comercial que envolve a arte de unir retalhos, divulga trabalhosLeia Mais","og_url":"https:\/\/floripaquilt.com.br\/10anos\/sobre\/","og_site_name":"Floripa Quilt","article_modified_time":"2023-04-23T23:44:31+00:00","og_image":[{"url":"https:\/\/floripaquilt.com.br\/10anos\/wp-content\/uploads\/2016\/10\/cropped-logo512px.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/floripaquilt.com.br\/10anos\/sobre\/","url":"https:\/\/floripaquilt.com.br\/10anos\/sobre\/","name":"10 Anos Floripa Quilt - Floripa Quilt","isPartOf":{"@id":"https:\/\/floripaquilt.com.br\/10anos\/#website"},"primaryImageOfPage":{"@id":"https:\/\/floripaquilt.com.br\/10anos\/sobre\/#primaryimage"},"image":{"@id":"https:\/\/floripaquilt.com.br\/10anos\/sobre\/#primaryimage"},"thumbnailUrl":"https:\/\/floripaquilt.com.br\/10anos\/wp-content\/uploads\/2016\/10\/cropped-logo512px.png","datePublished":"2007-09-04T17:48:10+00:00","dateModified":"2023-04-23T23:44:31+00:00","breadcrumb":{"@id":"https:\/\/floripaquilt.com.br\/10anos\/sobre\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/floripaquilt.com.br\/10anos\/sobre\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/floripaquilt.com.br\/10anos\/sobre\/#primaryimage","url":"https:\/\/floripaquilt.com.br\/10anos\/wp-content\/uploads\/2016\/10\/cropped-logo512px.png","contentUrl":"https:\/\/floripaquilt.com.br\/10anos\/wp-content\/uploads\/2016\/10\/cropped-logo512px.png","width":512,"height":512},{"@type":"BreadcrumbList","@id":"https:\/\/floripaquilt.com.br\/10anos\/sobre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/floripaquilt.com.br\/10anos\/"},{"@type":"ListItem","position":2,"name":"10 Anos Floripa Quilt"}]},{"@type":"WebSite","@id":"https:\/\/floripaquilt.com.br\/10anos\/#website","url":"https:\/\/floripaquilt.com.br\/10anos\/","name":"Floripa Quilt","description":"Floripa Quilt 2023 - 10\u00ba Festival de Patchwork e afins","publisher":{"@id":"https:\/\/floripaquilt.com.br\/10anos\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/floripaquilt.com.br\/10anos\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/floripaquilt.com.br\/10anos\/#organization","name":"Floripa Quilt","url":"https:\/\/floripaquilt.com.br\/10anos\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/floripaquilt.com.br\/10anos\/#\/schema\/logo\/image\/","url":"https:\/\/floripaquilt.com.br\/10anos\/wp-content\/uploads\/2022\/11\/logo_page-0001-2-e1676201734326.jpg","contentUrl":"https:\/\/floripaquilt.com.br\/10anos\/wp-content\/uploads\/2022\/11\/logo_page-0001-2-e1676201734326.jpg","width":70,"height":55,"caption":"Floripa Quilt"},"image":{"@id":"https:\/\/floripaquilt.com.br\/10anos\/#\/schema\/logo\/image\/"}}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/floripaquilt.com.br\/10anos\/wp-json\/wp\/v2\/pages\/156","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/floripaquilt.com.br\/10anos\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/floripaquilt.com.br\/10anos\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/floripaquilt.com.br\/10anos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/floripaquilt.com.br\/10anos\/wp-json\/wp\/v2\/comments?post=156"}],"version-history":[{"count":46,"href":"https:\/\/floripaquilt.com.br\/10anos\/wp-json\/wp\/v2\/pages\/156\/revisions"}],"predecessor-version":[{"id":8370,"href":"https:\/\/floripaquilt.com.br\/10anos\/wp-json\/wp\/v2\/pages\/156\/revisions\/8370"}],"wp:attachment":[{"href":"https:\/\/floripaquilt.com.br\/10anos\/wp-json\/wp\/v2\/media?parent=156"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}